{"id":203,"date":"2021-10-07T14:52:01","date_gmt":"2021-10-07T17:52:01","guid":{"rendered":"https:\/\/idonea.com.br\/blog\/?p=203"},"modified":"2021-10-08T15:31:33","modified_gmt":"2021-10-08T18:31:33","slug":"fim-do-flash-impacta-websites","status":"publish","type":"post","link":"https:\/\/idonea.com.br\/blog\/fim-do-flash-impacta-websites\/","title":{"rendered":"Como o fim do Adobe Flash Player impactar\u00e1 websites desenvolvidos com a tecnologia."},"content":{"rendered":"\n<p>A partir de 31 de dezembro de 2020, a Adobe n\u00e3o vai mais atualizar e tampouco distribuir o software multim\u00eddia Flash. Al\u00e9m disso, os maiores navegadores, como Google Chrome, Microsoft Edge e Mozilla Firefox ir\u00e3o desabilitar o Flash Player como padr\u00e3o e descontinuar totalmente o suporte.<\/p>\n\n\n\n<p>A plataforma de multim\u00eddia foi desenvolvida para aplica\u00e7\u00f5es com anima\u00e7\u00f5es, \u00e1udio e v\u00eddeo. O Adobe Flash Player se tornou um plugin de m\u00eddia para diversos navegadores e por muitos anos foi utilizado em websites.<\/p>\n\n\n\n<p>A verdade \u00e9 que desde 2017 a decis\u00e3o estava tomada pela Adobe em fun\u00e7\u00e3o de v\u00e1rios problemas com o software. A falta de seguran\u00e7a e o consumo excessivo de bateria para rodar os v\u00eddeos s\u00e3o duas raz\u00f5es essenciais, al\u00e9m dessas, tamb\u00e9m apresenta dificuldade de adapta\u00e7\u00e3o do plugin \u00e0s novas tecnologias sens\u00edveis ao toque, como a de celulares e at\u00e9 de alguns computadores.<\/p>\n\n\n\n<p><strong>E agora, com o fim do Flash, o que fazer?<\/strong><\/p>\n\n\n\n<p>\u00c9 fato que ao encerrar as atividades do Adobe Flash Player, a internet vai passar por algumas modifica\u00e7\u00f5es obrigatoriamente. Isso se aplica em especial \u00e0queles websites que ainda n\u00e3o atualizaram suas plataformas e permanecem utilizando o plugin para suas anima\u00e7\u00f5es, seus v\u00eddeos ou fotografias.<\/p>\n\n\n\n<p>Ent\u00e3o, se voc\u00ea possui p\u00e1gina na web baseada no Flash, \u00e9 tempo de buscar uma alternativa. E r\u00e1pido! Embora talvez voc\u00ea n\u00e3o saiba, o seu website j\u00e1 estava sendo afetado h\u00e1 anos por utilizar uma tecnologia defasada. O Google est\u00e1 se modificando desde 2016, ficando cada vez mais fechado ao Flash Player, al\u00e9m disso, diversas empresas desenvolvedoras de websites &#8211; como a Id\u00f4nea Comunica\u00e7\u00e3o, por exemplo &#8211; j\u00e1 migraram h\u00e1 muito tempo para outros softwares em raz\u00e3o dos problemas que se acumulavam na antiga plataforma.<\/p>\n\n\n\n<p><strong>Chrome e Firefox j\u00e1 n\u00e3o aceitam mais o Flash<\/strong><\/p>\n\n\n\n<p>Os dois navegadores mais utilizados mundialmente &#8211; Google Chrome e Mozilla Firefox &#8211; j\u00e1 anunciaram a data do fim do Flash. Com algumas manobras, ainda \u00e9 poss\u00edvel usar o plugin em ambos, mas depois do dia 31 de dezembro isso ser\u00e1 imposs\u00edvel no Chrome, enquanto a Mozilla ir\u00e1 encerrar a compatibilidade do Flash com o Firefox dia 26 de janeiro de 2021, data da pr\u00f3xima atualiza\u00e7\u00e3o do navegador..<\/p>\n\n\n\n<p><strong>Outras tecnologias podem substituir o Flash Player<\/strong><\/p>\n\n\n\n<p>Se atualmente voc\u00ea possui um site rodando em Flash Player, n\u00e3o faltam alternativas para substitu\u00ed-lo por tecnologias at\u00e9 mais avan\u00e7adas e seguras. Abaixo citamos algumas.<\/p>\n\n\n\n<p>Baseada no script &#8211; da\u00ed o seu nome &#8211; o&nbsp;<strong>JavaScript<\/strong>&nbsp;\u00e9 uma linguagem padronizada de programa\u00e7\u00e3o. Trata-se de uma tecnologia que encontra suporte na maior parte dos navegadores. E o melhor: o internauta n\u00e3o precisa instalar nenhum complemento para poder rodar seus v\u00eddeos, fotos ou anima\u00e7\u00f5es no site.<\/p>\n\n\n\n<p>Outro j\u00e1 exaustivamente empregado na internet, o HTML ganhou uma evolu\u00e7\u00e3o com o&nbsp;<strong>HTML5.<\/strong>&nbsp;A vers\u00e3o modernizada ganhou novos recursos, que d\u00e3o mais autonomia para o desenvolvedor e tornam o site mais leve e funcional. Uma das aplica\u00e7\u00f5es do HTML5, inclusive, \u00e9 permitir o uso de \u00e1udios e v\u00eddeos nos sites dispensando o uso do Flash.<\/p>\n\n\n\n<p>H\u00e1 tamb\u00e9m o&nbsp;<strong>CSS<\/strong>, que \u00e9 muito empregado no layout do site, ou seja, nas cores, fontes, espa\u00e7amentos e ajustes de imagens, por exemplo. Evolu\u00eddo, o CSS conta com o CSS Animation para ocupar o espa\u00e7o do Flash Player.<\/p>\n\n\n\n<p>Viu como s\u00e3o diversas as alternativas ao Adobe Flash Player? N\u00f3s da Id\u00f4nea estamos prontos para avaliar o seu site e apontar as melhores solu\u00e7\u00f5es para torn\u00e1-lo mais atraente, moderno e claro, funcional.<\/p>\n\n\n\n<p>Entre em&nbsp;<a href=\"https:\/\/idonea.com.br\/contato-agencia-publicidade-marketing.html\">contato<\/a>&nbsp;conosco, vamos conversar sobre como reformular seu website e utiliz\u00e1-lo em sua estrat\u00e9gia comercial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de 31 de dezembro de 2020, a Adobe n\u00e3o vai mais atualizar e tampouco distribuir o software multim\u00eddia Flash. Al\u00e9m disso, os maiores navegadores, como Google Chrome, Microsoft Edge e Mozilla Firefox ir\u00e3o desabilitar o Flash Player como padr\u00e3o e descontinuar totalmente o suporte. A plataforma de multim\u00eddia foi desenvolvida para aplica\u00e7\u00f5es com [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":242,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-203","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-websites"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Impactos do fim do Flash nos Websites | Id\u00f4nea Comunica\u00e7\u00e3o<\/title>\n<meta name=\"description\" content=\"Como o fim do Adobe Flash Player impactar\u00e1 websites desenvolvidos com a tecnologia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/idonea.com.br\/blog\/fim-do-flash-impacta-websites\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impactos do fim do Flash nos Websites | Id\u00f4nea Comunica\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"Como o fim do Adobe Flash Player impactar\u00e1 websites desenvolvidos com a tecnologia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/idonea.com.br\/blog\/fim-do-flash-impacta-websites\/\" \/>\n<meta property=\"og:site_name\" content=\"Id\u00f4nea\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-07T17:52:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-08T18:31:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/idonea.com.br\/blog\/wp-content\/uploads\/2021\/10\/flash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Id\u00f4nea Comunica\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Id\u00f4nea Comunica\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/fim-do-flash-impacta-websites\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/fim-do-flash-impacta-websites\\\/\"},\"author\":{\"name\":\"Id\u00f4nea Comunica\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/f318e46dafb39e80d2c2dc3795b61672\"},\"headline\":\"Como o fim do Adobe Flash Player impactar\u00e1 websites desenvolvidos com a tecnologia.\",\"datePublished\":\"2021-10-07T17:52:01+00:00\",\"dateModified\":\"2021-10-08T18:31:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/fim-do-flash-impacta-websites\\\/\"},\"wordCount\":651,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/fim-do-flash-impacta-websites\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/flash.jpg\",\"articleSection\":[\"Websites\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/idonea.com.br\\\/blog\\\/fim-do-flash-impacta-websites\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/fim-do-flash-impacta-websites\\\/\",\"url\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/fim-do-flash-impacta-websites\\\/\",\"name\":\"Impactos do fim do Flash nos Websites | Id\u00f4nea Comunica\u00e7\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/fim-do-flash-impacta-websites\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/fim-do-flash-impacta-websites\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/flash.jpg\",\"datePublished\":\"2021-10-07T17:52:01+00:00\",\"dateModified\":\"2021-10-08T18:31:33+00:00\",\"description\":\"Como o fim do Adobe Flash Player impactar\u00e1 websites desenvolvidos com a tecnologia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/fim-do-flash-impacta-websites\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/idonea.com.br\\\/blog\\\/fim-do-flash-impacta-websites\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/fim-do-flash-impacta-websites\\\/#primaryimage\",\"url\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/flash.jpg\",\"contentUrl\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/flash.jpg\",\"width\":2000,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/fim-do-flash-impacta-websites\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como o fim do Adobe Flash Player impactar\u00e1 websites desenvolvidos com a tecnologia.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/\",\"name\":\"Id\u00f4nea\",\"description\":\"Consultoria em Comunica\u00e7\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/#organization\",\"name\":\"Id\u00f4nea\",\"url\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-idonea-comunicacao.svg\",\"contentUrl\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-idonea-comunicacao.svg\",\"width\":66,\"height\":18,\"caption\":\"Id\u00f4nea\"},\"image\":{\"@id\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/f318e46dafb39e80d2c2dc3795b61672\",\"name\":\"Id\u00f4nea Comunica\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ca9b110f6b70ee29eca70b2f0f5cef72b092083fc2c446faae973e015e77bae?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ca9b110f6b70ee29eca70b2f0f5cef72b092083fc2c446faae973e015e77bae?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ca9b110f6b70ee29eca70b2f0f5cef72b092083fc2c446faae973e015e77bae?s=96&d=mm&r=g\",\"caption\":\"Id\u00f4nea Comunica\u00e7\u00e3o\"},\"sameAs\":[\"https:\\\/\\\/idonea.com.br\\\/blog\"],\"url\":\"https:\\\/\\\/idonea.com.br\\\/blog\\\/author\\\/idonea\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impactos do fim do Flash nos Websites | Id\u00f4nea Comunica\u00e7\u00e3o","description":"Como o fim do Adobe Flash Player impactar\u00e1 websites desenvolvidos com a tecnologia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/idonea.com.br\/blog\/fim-do-flash-impacta-websites\/","og_locale":"pt_BR","og_type":"article","og_title":"Impactos do fim do Flash nos Websites | Id\u00f4nea Comunica\u00e7\u00e3o","og_description":"Como o fim do Adobe Flash Player impactar\u00e1 websites desenvolvidos com a tecnologia.","og_url":"https:\/\/idonea.com.br\/blog\/fim-do-flash-impacta-websites\/","og_site_name":"Id\u00f4nea","article_published_time":"2021-10-07T17:52:01+00:00","article_modified_time":"2021-10-08T18:31:33+00:00","og_image":[{"width":2000,"height":400,"url":"https:\/\/idonea.com.br\/blog\/wp-content\/uploads\/2021\/10\/flash.jpg","type":"image\/jpeg"}],"author":"Id\u00f4nea Comunica\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Id\u00f4nea Comunica\u00e7\u00e3o","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/idonea.com.br\/blog\/fim-do-flash-impacta-websites\/#article","isPartOf":{"@id":"https:\/\/idonea.com.br\/blog\/fim-do-flash-impacta-websites\/"},"author":{"name":"Id\u00f4nea Comunica\u00e7\u00e3o","@id":"https:\/\/idonea.com.br\/blog\/#\/schema\/person\/f318e46dafb39e80d2c2dc3795b61672"},"headline":"Como o fim do Adobe Flash Player impactar\u00e1 websites desenvolvidos com a tecnologia.","datePublished":"2021-10-07T17:52:01+00:00","dateModified":"2021-10-08T18:31:33+00:00","mainEntityOfPage":{"@id":"https:\/\/idonea.com.br\/blog\/fim-do-flash-impacta-websites\/"},"wordCount":651,"commentCount":0,"publisher":{"@id":"https:\/\/idonea.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/idonea.com.br\/blog\/fim-do-flash-impacta-websites\/#primaryimage"},"thumbnailUrl":"https:\/\/idonea.com.br\/blog\/wp-content\/uploads\/2021\/10\/flash.jpg","articleSection":["Websites"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/idonea.com.br\/blog\/fim-do-flash-impacta-websites\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/idonea.com.br\/blog\/fim-do-flash-impacta-websites\/","url":"https:\/\/idonea.com.br\/blog\/fim-do-flash-impacta-websites\/","name":"Impactos do fim do Flash nos Websites | Id\u00f4nea Comunica\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/idonea.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/idonea.com.br\/blog\/fim-do-flash-impacta-websites\/#primaryimage"},"image":{"@id":"https:\/\/idonea.com.br\/blog\/fim-do-flash-impacta-websites\/#primaryimage"},"thumbnailUrl":"https:\/\/idonea.com.br\/blog\/wp-content\/uploads\/2021\/10\/flash.jpg","datePublished":"2021-10-07T17:52:01+00:00","dateModified":"2021-10-08T18:31:33+00:00","description":"Como o fim do Adobe Flash Player impactar\u00e1 websites desenvolvidos com a tecnologia.","breadcrumb":{"@id":"https:\/\/idonea.com.br\/blog\/fim-do-flash-impacta-websites\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/idonea.com.br\/blog\/fim-do-flash-impacta-websites\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/idonea.com.br\/blog\/fim-do-flash-impacta-websites\/#primaryimage","url":"https:\/\/idonea.com.br\/blog\/wp-content\/uploads\/2021\/10\/flash.jpg","contentUrl":"https:\/\/idonea.com.br\/blog\/wp-content\/uploads\/2021\/10\/flash.jpg","width":2000,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/idonea.com.br\/blog\/fim-do-flash-impacta-websites\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/idonea.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Como o fim do Adobe Flash Player impactar\u00e1 websites desenvolvidos com a tecnologia."}]},{"@type":"WebSite","@id":"https:\/\/idonea.com.br\/blog\/#website","url":"https:\/\/idonea.com.br\/blog\/","name":"Id\u00f4nea","description":"Consultoria em Comunica\u00e7\u00e3o","publisher":{"@id":"https:\/\/idonea.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/idonea.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/idonea.com.br\/blog\/#organization","name":"Id\u00f4nea","url":"https:\/\/idonea.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/idonea.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/idonea.com.br\/blog\/wp-content\/uploads\/2021\/09\/logo-idonea-comunicacao.svg","contentUrl":"https:\/\/idonea.com.br\/blog\/wp-content\/uploads\/2021\/09\/logo-idonea-comunicacao.svg","width":66,"height":18,"caption":"Id\u00f4nea"},"image":{"@id":"https:\/\/idonea.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/idonea.com.br\/blog\/#\/schema\/person\/f318e46dafb39e80d2c2dc3795b61672","name":"Id\u00f4nea Comunica\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/2ca9b110f6b70ee29eca70b2f0f5cef72b092083fc2c446faae973e015e77bae?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ca9b110f6b70ee29eca70b2f0f5cef72b092083fc2c446faae973e015e77bae?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ca9b110f6b70ee29eca70b2f0f5cef72b092083fc2c446faae973e015e77bae?s=96&d=mm&r=g","caption":"Id\u00f4nea Comunica\u00e7\u00e3o"},"sameAs":["https:\/\/idonea.com.br\/blog"],"url":"https:\/\/idonea.com.br\/blog\/author\/idonea\/"}]}},"_links":{"self":[{"href":"https:\/\/idonea.com.br\/blog\/wp-json\/wp\/v2\/posts\/203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/idonea.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/idonea.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/idonea.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/idonea.com.br\/blog\/wp-json\/wp\/v2\/comments?post=203"}],"version-history":[{"count":1,"href":"https:\/\/idonea.com.br\/blog\/wp-json\/wp\/v2\/posts\/203\/revisions"}],"predecessor-version":[{"id":205,"href":"https:\/\/idonea.com.br\/blog\/wp-json\/wp\/v2\/posts\/203\/revisions\/205"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/idonea.com.br\/blog\/wp-json\/wp\/v2\/media\/242"}],"wp:attachment":[{"href":"https:\/\/idonea.com.br\/blog\/wp-json\/wp\/v2\/media?parent=203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/idonea.com.br\/blog\/wp-json\/wp\/v2\/categories?post=203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/idonea.com.br\/blog\/wp-json\/wp\/v2\/tags?post=203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}